{"id":10175,"date":"2022-07-22T15:39:09","date_gmt":"2022-07-22T18:39:09","guid":{"rendered":"https:\/\/www.bienaldelchaco.org\/2024\/?p=10175"},"modified":"2022-07-25T15:41:39","modified_gmt":"2022-07-25T18:41:39","slug":"con-mas-de-80-000-visitantes-diarios-la-escultura-toma-protagonismo-en-la-bienal-de-chaco","status":"publish","type":"post","link":"https:\/\/www.bienaldelchaco.org\/2024\/con-mas-de-80-000-visitantes-diarios-la-escultura-toma-protagonismo-en-la-bienal-de-chaco\/","title":{"rendered":"Con m\u00e1s de 80.000 visitantes diarios, la escultura toma protagonismo en la Bienal de Chaco"},"content":{"rendered":"<p>Unas 80 mil personas por d\u00eda recorren la amplia oferta cultural de la Bienal de Esculturas de Chaco. Se puede disfrutar de actividades para chicos, exposiciones de obras de artistas chaque\u00f1os y de los seleccionados para la competencia internacional de escultura, espacios para la reflexi\u00f3n acad\u00e9mica y una impactante feria de artesan\u00edas.<\/p>\n<div id=\"galeria-trigger\" class=\"entry-media no-p main-image pointer col-lg-12 col-md-12 \"><picture class=\"ppalFigure clip lazy_2\"><source srcset=\"https:\/\/www.clarin.com\/img\/2022\/07\/22\/derrumbe-la-instalacion-sonora-del___pSNF865Kn_1256x620__1.jpg\" media=\"(min-width: 720px)\" \/><\/picture><\/div>\n<div class=\"td-module-meta-info\"><\/div>\n<p><!--more-->[vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221;][vc_column][vc_column_text]Unas 80 mil personas por d\u00eda recorren la amplia oferta cultural de la Bienal de Esculturas de Chaco, donde obras ef\u00edmeras en arena como las de Alejandro Arce o el muro de Juan Sorrentino que se derrumba por la vibraci\u00f3n sonora suscitan la atenci\u00f3n del p\u00fablico en este encuentro que suma un programa de accesibilidad para que personas ciegas puedan realizar un recorrido t\u00e1ctil y desentra\u00f1ar los vol\u00famenes del m\u00e1rmol que 10 escultores de todo el mundo est\u00e1n culminando a cielo abierto en el marco de la competencia internacional.<\/p>\n<p>Actividades para chicos, exposiciones de obras de artistas chaque\u00f1os y de los seleccionados para la competencia internacional de escultura, espacios para la reflexi\u00f3n acad\u00e9mica y una impactante feria de artesan\u00edas que re\u00fane a artesanos variados del pa\u00eds y de pueblos originarios, entre otras expresiones art\u00edsticas, conviven por estos d\u00edas en m\u00e1s de 9 hect\u00e1reas de un total de 14 que forman parte del Parque 2 de Febrero, donde se desarrolla la Bienal Internacional del Chaco con acceso libre y gratuito.<\/p>\n<p>El recorrido obligado para quienes visitan la competencia escult\u00f3rica a cielo abierto, una de las m\u00e1s importantes del mundo, convoca la curiosidad y la mirada experta sobre un trabajo en proceso que m\u00e1s all\u00e1 del polvo que envuelve el espacio de los escultores -provenientes de Asia, Europa y Am\u00e9rica Latina trabajan-, mantiene un continuo flujo de miradas interesadas, expertas, cr\u00edticas y m\u00e1s numerosas en horas de la tarde. Un espacio en el que la gente interact\u00faa con los artistas y donde el c\u00e1lido ofrecimiento de agua para mate o alg\u00fan bocadillo de los vecinos, es uno de los detalles relevantes de la competencia gestada por la dupla creativa del fallecido artista Fabriciano G\u00f3mez y la escultora Mimo Eidman.<\/p>\n<figure class=\"mb-3\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10178 alignnone\" src=\"https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/07\/62db1e5459c80_900.jpg\" alt=\"\" width=\"900\" height=\"506\" srcset=\"https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/07\/62db1e5459c80_900.jpg 900w, https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/07\/62db1e5459c80_900-300x169.jpg 300w, https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/07\/62db1e5459c80_900-768x432.jpg 768w, https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/07\/62db1e5459c80_900-700x394.jpg 700w, https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/07\/62db1e5459c80_900-539x303.jpg 539w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/p>\n<div class=\"media-icons\"><\/div><figcaption>Foto: Pablo Caprarulo<\/figcaption><\/figure>\n<p>Esta interacci\u00f3n entre escultor y p\u00fablico es el dato relevante de la Bienal, que funciona como un permiso para acceder al taller del artista, al aire libre, durante siete d\u00edas, una instancia que remite al hecho fundacional desde ese primer encuentro que tuvo lugar en 1988 en la plaza 25 de Mayo y que en la actualidad acumula un legado patrimonial de 654 esculturas de relevantes artistas generado a lo largo de las distintas ediciones, seg\u00fan contabiliza Juan Sebasti\u00e1n Eidman, presidente de la Fundaci\u00f3n Urunday que organiza el evento junto a la gobernaci\u00f3n de la provincia, convertida hoy en un gran museo al aire libre.<\/p>\n<p>Pero esta XII Bienal Internacional de Escultura 2022 tambi\u00e9n convoca al arte ef\u00edmero, como el de Alejandro Arce con su grupo escult\u00f3rico dedicado al oso &#8220;Jukumari&#8221; -una especie de la regi\u00f3n andina en peligro de extinci\u00f3n- realizado en arena, punto de atracci\u00f3n para los ni\u00f1os. Contiguo a esta escultura se encuentra otra de menor tama\u00f1o, &#8220;El chaj\u00e1&#8221;, un ave en madera que trabaja Gerardo Aranda, representante de los pueblos originarios. Y la tambi\u00e9n ef\u00edmera obra de Fabiana Larrea, llamada &#8220;El ciclo de las cosas&#8221;: tres flores realizadas con pl\u00e1stico reciclado que configuran desde el vamos la transformaci\u00f3n como recurso simb\u00f3lico y concreto, sobre el r\u00edo Negro, que regresar\u00e1n luego a la f\u00e1brica que suministr\u00f3 su materia prima.<\/p>\n<p>Por su parte, Juan Sorrentino presenta su proyecto &#8220;Derrumbe&#8221;: una pared de ladrillo, fierros, revestimiento y pintura que es creada y modificada al ser expuesta a la vibraci\u00f3n sonora de frecuencias graves, tan caracter\u00edstica de su experiencia como artista sonoro y visual. No solo el muro vibra y se va &#8220;destruyendo&#8221;, sino que el piso de tierra del parque transmite esas vibraciones al p\u00fablico, que observa los desprendimientos de la obra, tal como lo se\u00f1ala el propio artista chaque\u00f1o que reside en Buenos Aires.<\/p>\n<figure class=\"mb-3\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10177 alignnone\" src=\"https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/07\/62db1e6db728b_900.jpg\" alt=\"\" width=\"900\" height=\"506\" srcset=\"https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/07\/62db1e6db728b_900.jpg 900w, https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/07\/62db1e6db728b_900-300x169.jpg 300w, https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/07\/62db1e6db728b_900-768x432.jpg 768w, https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/07\/62db1e6db728b_900-700x394.jpg 700w, https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/07\/62db1e6db728b_900-539x303.jpg 539w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/p>\n<div class=\"media-icons\"><\/div><figcaption>Foto: Pablo Caprarulo<\/figcaption><\/figure>\n<p>Tambi\u00e9n, aunque a\u00fan inacabada, est\u00e1 la propuesta de Gerardo Suter, &#8220;Murmullos&#8221;, una estructura de madera que reproduce un gran trailer para generar la experiencia inmersiva de ser, por unos instantes, uno m\u00e1s en esa masa de migrantes que cruza la frontera inh\u00f3spita y mortal en su tr\u00e1nsito desde M\u00e9xico a Estados Unidos.<\/p>\n<p>Todos estos artistas argentinos invitados al &#8220;Encuentro de escultores&#8221;, trabajan sus obras con libertad de t\u00e9cnicas y materiales, por fuera de la competencia, y entre ellos tambi\u00e9n est\u00e1n Norma Siguelboim y Monica Souza.<\/p>\n<p>Pero el foco de la Bienal, que se irradia como motor de la industria cultural provincial, comenz\u00f3 con esos diez bloques de m\u00e1rmol travertino proporcionado para el Concurso Internacional de Escultura 2022. Todos diferentes si bien de dimensiones similares, entregados a los escultores hace escasos d\u00edas, y que incluso obligaron a replantear proyectos originales como el del alban\u00e9s Genti Tavanxhiu -que pas\u00f3 de su &#8220;Re-cycladis&#8221; a una &#8220;Se\u00f1orita&#8221;- o a adecuar ante una porosidad o agujeros imprevistos del bloque asignado, como en el caso del argentino Juan Pablo Marturano con &#8220;M\u00e1s all\u00e1 de las nubes&#8221;.<\/p>\n<p>Los otros participantes son las escultoras Verena Mayer-Tasch (Alemania) y Ebru Akinci (Turqu\u00eda), David Bucio (M\u00e9xico), Sodong Choe (Corea del Sur), Arijel Strukelj (Eslovenia), Jhon Gogaberishvili (Georgia), Petre Virgiliu Mogosanu (Rumania) y el ucraniano Ihor Tkachivskyi.<\/p>\n<p>Otra de las atracciones de esta Bienal fue la competencia &#8220;Hierros L\u00edder&#8221;, destinada a estudiantes de artes de universidades e institutos art\u00edsticos del pa\u00eds con la consigna de realizar una escultura en 48 horas continuas y con 48 participantes en equipos de 13 provincias, que cerr\u00f3 su edici\u00f3n del jueves.<\/p>\n<p>La accesibilidad es otro de los fuertes de la Bienal expandida como experiencia 2022, desde la posibilidad de &#8220;ver con las manos&#8221; para personas ciegas, a partir de un proyecto que nuclea a 20 organizaciones en la Red de Accesibilidad Cultural impulsado desde el Centro Cultural Alternativo (Cecual). La propuesta trabaja en la Bienal junto a la Fundaci\u00f3n con cuatro ejes: capacitaci\u00f3n; comunicaci\u00f3n desde c\u00f3digos QR a escritura en braile; infraestructura con adecuaci\u00f3n edilicia del espacio que es m\u00e1s grande que en ediciones previas; y por \u00faltimo programaci\u00f3n y contenidos tales como radio abierta y visitas guiadas por audiodescripci\u00f3n, entre otras.<\/p>\n<p>En la experiencia concreta, el escultor detiene su trabajo y deja que la persona con alg\u00fan tipo de discapacidad visual recorra con sus manos las formas y texturas del volumen en proceso, de ese granito sanjuanino, para que pueda sentirlas desde un lugar ajeno a la mayor\u00eda de los visitantes que le permite ser part\u00edcipe de un intercambio \u00edntimo y p\u00fablico, a la vez que lo incluye en ese di\u00e1logo colectivo que finaliza con la premiaci\u00f3n.<\/p>\n<p>Es la primera vez que en el marco de la Bienal se realiza esta experiencia de audio descripci\u00f3n, de accesibilidad, algo que se prolonga en otras actividades y abarca distintas discapacidades, con herramientas pensadas desde el espacio de la propia web del evento, como otra forma de conocer e incluir en esa apuesta de un arte para todos propuesto.<\/p>\n<figure class=\"mb-3\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10176 alignnone\" src=\"https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/07\/62db1e6da421a_900.jpg\" alt=\"\" width=\"900\" height=\"506\" srcset=\"https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/07\/62db1e6da421a_900.jpg 900w, https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/07\/62db1e6da421a_900-300x169.jpg 300w, https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/07\/62db1e6da421a_900-768x432.jpg 768w, https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/07\/62db1e6da421a_900-700x394.jpg 700w, https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/07\/62db1e6da421a_900-539x303.jpg 539w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/p>\n<div class=\"media-icons\"><\/div><figcaption>Foto: Pablo Caprarulo<\/figcaption><\/figure>\n<p>Otro de los espacios innovadores es el del &#8220;Arte en miniatura&#8221;, donde en un stand, varias impresoras 3D replican dos de las esculturas de Fabriciano G\u00f3mez, las que est\u00e1n instaladas en el exterior de la Catedral de la ciudad y no est\u00e1n re\u00f1idas con derechos de autor para su copia. All\u00ed, por una suma que oscila entre 250 y 1000 pesos, el visitante puede llevarse como recuerdo una peque\u00f1a estatuilla, que demora por lo menos unas cuatro horas de impresi\u00f3n.<\/p>\n<p>Tambi\u00e9n se puede observar c\u00f3mo se van construyendo estas figuras en blanco o marr\u00f3n de material pl\u00e1stico reciclable, con impresoras fabricadas por una firma radicada en Lan\u00fas.<\/p>\n<p>Para el titular del emprendimiento, Rub\u00e9n Kuttercraft, &#8220;el arte de la Bienal se va a ver reflejada en todo el mundo&#8221; en esa gran vidriera de internet con est\u00e1s r\u00e9plicas a partir de modelos digitalizados con esc\u00e1neres tridimensionales, llevadas a cabo desde el programa que impulsa la local Veta Noble. Un proyecto que busca resguardar de otro modo el patrimonio de Resistencia al digitalizarlo para que las personas puedan tener estas esculturas en sus hogares.<\/p>\n<p>Una ecuaci\u00f3n que busca popularizar las creaciones patrimoniales de esas 500 obras producto de competencias y bienales durante 34 a\u00f1os de trabajo, que se suman a las 100 previas que ya ten\u00eda la ciudad desde mediados de la d\u00e9cada de 1940, e instala la tecnolog\u00eda como herramienta del patrimonio escult\u00f3rico y generaci\u00f3n de trabajo.<\/p>\n<p>Con la visita de 600.000 personas en la anterior edici\u00f3n de 2018, las expectativas actuales de los organizadores superan esa cifra, tal como la numerosa afluencia de personas el domingo pasado o el c\u00e1lculo de las 80 mil personas que se acercaron a escuchar el recital de Juan Carlos Baglietto y Lito Vitale la noche del mi\u00e9rcoles. La m\u00fasica es otro de los atractivos del evento.<\/p>\n<p>Por otro lado, la competencia internacional reparte 50.000 d\u00f3lares desde la Bienal organizada por la Fundaci\u00f3n Urunday, 5.000 d\u00f3lares para cada escultor que adem\u00e1s recibe el certificado del premio que haya ganado -que tendr\u00e1 su momento cumbre este s\u00e1bado-, seg\u00fan la decisi\u00f3n del jurado integrado por los escultores Le\u00f3n Saavedra Geuer (Bolivia), Francisco Gazit\u00faa (Chile) y el b\u00falgaro Todor Todorov. Es as\u00ed que se dan tres premios y cinco menciones especiales, adem\u00e1s del voto del p\u00fablico, el de los ni\u00f1os y el de los propios pares que compartieron la proximidad de la creaci\u00f3n. Quedar\u00e1 la inc\u00f3gnita a ser develada sobre si vuelve a coincidir el voto del p\u00fablico con el de los jurados, una tendencia que parece estar en sinton\u00eda en las \u00faltimas ediciones.[\/vc_column_text][\/vc_column][\/vc_row][vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221;][vc_column][vc_empty_space][vc_column_text]Fuente:\u00a0 <a href=\"https:\/\/www.telam.com.ar\/notas\/202207\/599363-bienal-de-chaco-cultura.html\" target=\"_blank\" rel=\"noopener\">https:\/\/www.telam.com.ar\/notas\/202207\/599363-bienal-de-chaco-cultura.html<\/a>[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221;][vc_column][vc_column_text]\n[\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>Unas 80 mil personas por d\u00eda recorren la amplia oferta cultural de la Bienal de Esculturas de Chaco. Se puede disfrutar de actividades para chicos, exposiciones de obras de artistas chaque\u00f1os y de los seleccionados para la competencia internacional de escultura, espacios para la reflexi\u00f3n&#8230;<\/p>\n","protected":false},"author":3,"featured_media":10179,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-10175","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novedades"],"_links":{"self":[{"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/posts\/10175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/comments?post=10175"}],"version-history":[{"count":1,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/posts\/10175\/revisions"}],"predecessor-version":[{"id":10180,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/posts\/10175\/revisions\/10180"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/media\/10179"}],"wp:attachment":[{"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/media?parent=10175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/categories?post=10175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/tags?post=10175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}