{"id":10391,"date":"2022-07-26T16:44:01","date_gmt":"2022-07-26T19:44:01","guid":{"rendered":"https:\/\/www.bienaldelchaco.org\/2024\/?p=10391"},"modified":"2022-07-29T16:44:12","modified_gmt":"2022-07-29T19:44:12","slug":"una-obra-de-susana-panza-seleccionada-en-la-bienal-del-chaco-2022","status":"publish","type":"post","link":"https:\/\/www.bienaldelchaco.org\/2024\/una-obra-de-susana-panza-seleccionada-en-la-bienal-del-chaco-2022\/","title":{"rendered":"Una obra de Susana Panza, seleccionada en la Bienal del Chaco 2022"},"content":{"rendered":"<div class=\"col-md-12 col-xs-12\">\n<div class=\"bajada\">\n<div class=\"bajada\">La artista local particip\u00f3 en &#8220;Placas de Artistas en Vidrio&#8221;, una convocatoria realizada en el marco del V Encuentro de Maestros Artesanos Argentinos de la Bienal Internacional de Esculturas de Chaco, y en el A\u00f1o Internacional del Vidrio.<\/div>\n<div id=\"texto_tpl6\" class=\"texto\">\n<div class=\"banner-portada\">\n<div id=\"MobileBanner_1\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"col-md-12 col-xs-12\">\n<div class=\"bajada\">\n<div class=\"byline\"><\/div>\n<\/div>\n<\/div>\n<p><!--more-->[vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221;][vc_column][vc_column_text]Del 16 al 23 de julio se llev\u00f3 a cabo en Resistencia, la Bienal del Chaco 2022. Dicho evento incluy\u00f3 la XII Bienal Internacional de Escultura, el VIII Encuentro de Escultores Invitados, el VIII Concurso de Escultura para Estudiantes de Artes, el III Congreso Internacional de Artes, el II Seminario de Arte, Derecho, Patrimonio y Urbanismo, el I Congreso Internacional de Derecho del Arte, el IV Festival Filarm\u00f3nico Juvenil, el V Encuentro de Maestros Artesanos Argentinos y el VII Encuentro de Artesanos de Pueblos Originarios.<\/p>\n<p>En el marco del V Encuentro de Maestros Artesanos Argentinos de la Bienal Internacional de Esculturas de Chaco, y en el A\u00f1o Internacional del Vidrio, se realiz\u00f3 la convocatoria internacional &#8220;Placas de Artistas en Vidrio&#8221;, de la que participaron artistas de todo el mundo.<\/p>\n<p>De nuestra ciudad particip\u00f3 con una placa de vidrio intervenida la artista visual Susana Panza.<\/p>\n<p>En esta nueva convocatoria enfocada en el vidrio, se realizaron varios murales que fueron emplazados en distintos lugares p\u00fablicos y al aire libre, de la ciudad de Resistencia, que podr\u00e1n ser visitados por turismo nacional e internacional.<\/p>\n<p>Los murales terminados se publicar\u00e1n en los sitios oficiales de los organizadores con los nombres de todos los participantes que decidan donar su placa.<\/p>\n<p>&#8220;Hab\u00eda que enviar una placa de 20 cm x 20 cm. Yo trabaj\u00e9 con un vidrio rojo que completa una figura de vidrio negro con textura e irisdicencia y una gema roja. Se llama Antoine&#8221;, coment\u00f3 Panza en contacto con LA OPINION.<\/p>\n<p>La artista viene de hacer un roset\u00f3n para la Iglesia Mar\u00eda Auxiliadora de Fontezuela, que ser\u00e1 instalado en breve. Tambi\u00e9n realiz\u00f3 un vitral cenital o claraboya de 3 mt. X 150. &#8220;Esta es una escultura que pronto colocaremos es el Silfo que en su soplo lleva la m\u00fasica del viento&#8221;, explic\u00f3, al tiempo que adelant\u00f3 que se encuentra trabajando en una serie de retratos que pronto dar\u00e1 a conocer.[\/vc_column_text][\/vc_column][\/vc_row][vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221;][vc_column][vc_empty_space][vc_gallery interval=&#8221;3&#8243; images=&#8221;10388,10387&#8243; img_size=&#8221;full&#8221;][vc_empty_space][vc_column_text]Fuente:\u00a0 <a href=\"https:\/\/laopinionpergamino.com.ar\/nota\/8931\/2022\/07\/una-obra-de-susana-panza-seleccionada-en-la-bienal-del-chaco-2022\" target=\"_blank\" rel=\"noopener\">https:\/\/laopinionpergamino.com.ar\/nota\/8931\/2022\/07\/una-obra-de-susana-panza-seleccionada-en-la-bienal-del-chaco-2022<\/a>[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>La artista local particip\u00f3 en &#8220;Placas de Artistas en Vidrio&#8221;, una convocatoria realizada en el marco del V Encuentro de Maestros Artesanos Argentinos de la Bienal Internacional de Esculturas de Chaco, y en el A\u00f1o Internacional del Vidrio.<\/p>\n","protected":false},"author":3,"featured_media":10387,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-10391","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novedades"],"_links":{"self":[{"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/posts\/10391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/comments?post=10391"}],"version-history":[{"count":1,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/posts\/10391\/revisions"}],"predecessor-version":[{"id":10392,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/posts\/10391\/revisions\/10392"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/media\/10387"}],"wp:attachment":[{"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/media?parent=10391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/categories?post=10391"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/tags?post=10391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}