{"id":10512,"date":"2022-08-02T17:04:56","date_gmt":"2022-08-02T20:04:56","guid":{"rendered":"https:\/\/www.bienaldelchaco.org\/2024\/?p=10512"},"modified":"2022-08-02T17:13:37","modified_gmt":"2022-08-02T20:13:37","slug":"de-hijo-de-sereno-de-plaza-a-escultor-llevado-en-andas-por-la-gente-vida-y-obra-del-chaqueno-fabriciano-gomez","status":"publish","type":"post","link":"https:\/\/www.bienaldelchaco.org\/2024\/de-hijo-de-sereno-de-plaza-a-escultor-llevado-en-andas-por-la-gente-vida-y-obra-del-chaqueno-fabriciano-gomez\/","title":{"rendered":"De hijo de sereno de plaza a escultor llevado en andas por la gente: vida y obra del chaque\u00f1o Fabriciano G\u00f3mez"},"content":{"rendered":"<p class=\"article-subheadline\">El creador de la Bienal Internacional de Escultura del Chaco muri\u00f3 el 8 de septiembre de 2021, a los 77 a\u00f1os. Poco antes, dec\u00eda: \u201cMe voy como vine, sin nada, liviano, pero con la carga interior de haber sido un afortunado en la vida y de poder decir \u2018he cumplido\u2019\u201d<\/p>\n<div class=\"byline\"><\/div>\n<p><!--more-->[vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221;][vc_column][vc_column_text]\n<p class=\"paragraph\">En el Chaco\u00a0<b>basta con decir su nombre de pila, Fabriciano<\/b>, para que todo el mundo sepa de qui\u00e9n se trata. El suyo es\u00a0<b>el raro caso de un escultor que ha gozado en vida de una popularidad<\/b>\u00a0comparable a la que tienen actores o cantantes.<\/p>\n<p class=\"paragraph\">\u201cResistencia tiene magia\u201d, dec\u00eda \u00e9l, y sin duda\u00a0<b>Fabriciano G\u00f3mez fue parte de esa magia de la ciudad<\/b>\u00a0que lo vio nacer y en la que tanta huella ha dejado.<\/p>\n<p class=\"paragraph\">En 1994, Fabriciano y otros dos colegas, Humberto G\u00f3mez Lollo y Walter Sotelo,\u00a0<b>ganaron la medalla de oro en las Olimp\u00edadas de Arte de Noruega,<\/b>\u00a0esculpiendo un bloque de hielo. M\u00e1s all\u00e1 de la paradoja de que artistas originarios de una provincia donde puede hacer 30 grados en invierno ganaran una competencia de escultura en hielo, para los resistencianos la noticia fue movilizante.\u00a0<b>Una multitud esper\u00f3 a los escultores en el aeropuerto de la capital chaque\u00f1a para llevarlos en caravana triunfal\u00a0<\/b>hasta el centro de la Ciudad como si se tratase del seleccionado de f\u00fatbol.<\/p>\n<p class=\"paragraph\"><b>VIDEO: Regreso con gloria de los escultores chaque\u00f1os, con la medalla de oro de las Olimp\u00edadas de Arte de Noruega<\/b><\/p>\n<div class=\"jwplayer-ctn\">\n<div>\n<div id=\"seGLJyiA\" class=\"jwplayer jw-reset jw-state-idle jw-stretch-uniform jw-flag-aspect-mode jw-floating-dismissible jw-breakpoint-4 jw-flag-user-inactive\" tabindex=\"0\" role=\"application\" aria-label=\"Reproductor de Video\">\n<div class=\"jw-wrapper jw-reset\">\n<div class=\"jw-controls jw-reset\">\n<div class=\"jw-nextup-container jw-reset\">\n<div class=\"jw-nextup jw-background-color jw-reset jw-nextup-thumbnail-visible\">\n<p><iframe loading=\"lazy\" src=\"\/\/content.jwplatform.com\/players\/seGLJyiA-a9NdgpIU.html\" width=\"640\" height=\"360\" frameborder=\"0\" scrolling=\"auto\"><\/iframe><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>Fabriciano G\u00f3mez &#8211; escultura en hielo<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<p class=\"paragraph\">Como se\u00f1ala el video de la Fundaci\u00f3n Urunday, ese hecho represent\u00f3\u00a0<b>\u201cla verdadera consagraci\u00f3n del artista\u201d,<\/b>\u00a0a trav\u00e9s del amor de la gente. Pero ese estallido de popularidad se ven\u00eda gestando desde antes, motivado por el rol social que ya desempe\u00f1aba Fabriciano G\u00f3mez en Resistencia, a la vez que enraizado en una tradici\u00f3n de la ciudad.<\/p>\n<p class=\"paragraph\">\u201cUn historiador nuestro, Guido Miranda, dice que el inmigrante italiano que pobl\u00f3 la colonia Resistencia mir\u00f3, durante mucho tiempo, la tierra que cultivaba y no la luna que da alas al poeta; enfocado exclusivamente en el sacrificio del trabajo, en el progreso material de sus d\u00edas, en lo esencial miraba el surco y no las estrellas\u201d, dijo a<b>\u00a0Infobae<\/b>\u00a0el periodista y escritor chaque\u00f1o\u00a0<b>Marcelo Nieto,<\/b>\u00a0autor de una biograf\u00eda sobre Fabriciano.<\/p>\n<p class=\"paragraph\">Despu\u00e9s cambi\u00f3 todo:\u00a0<b>\u201cEl tiempo hizo a Resistencia art\u00edstica y cultural\u00a0<\/b>-describi\u00f3-. Aqu\u00ed, el arte siempre tuvo prensa respetuosa, y escultores como\u00a0<b>Crisanto Dom\u00ednguez, Juan de Dios Mena o Carlos Schenone\u00a0<\/b>contaron con la admiraci\u00f3n de sus compoblanos\u201d.<\/p>\n<p class=\"paragraph\">Fabriciano G\u00f3mez, por su parte,\u00a0<b>conoci\u00f3 muy joven el reconocimiento a su obra<\/b>. \u201cEra apenas un muchacho cuando recibe el\u00a0<b>Primer Premio del Sal\u00f3n Nacional<\/b>\u00a0y no pasa rato que ya obtiene el\u00a0<b>Gran Premio de Honor<\/b>; representa a la Argentina en la\u00a0<b>Bienal de Venecia de 1980<\/b>\u00a0y a continuaci\u00f3n, se embala en la experiencia de concursar en\u00a0<b>competencias de hielo y nieve<\/b>\u00a0por el mundo. De donde trae grandes preseas tambi\u00e9n. En uno de aquellos viajes, volviendo de los confines del mundo con un primer premio, hay un pueblo en el aeropuerto,\u00a0<b>una caravana nunca vista\u2026<\/b>\u201d, recuerda Marcelo Nieto.<\/p>\n<p class=\"paragraph\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10514 alignnone\" src=\"https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/08\/D4WIQRD2IFEE5NQCM3N6TVLU7U.jpg\" alt=\"\" width=\"992\" height=\"558\" srcset=\"https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/08\/D4WIQRD2IFEE5NQCM3N6TVLU7U.jpg 992w, https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/08\/D4WIQRD2IFEE5NQCM3N6TVLU7U-300x169.jpg 300w, https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/08\/D4WIQRD2IFEE5NQCM3N6TVLU7U-768x432.jpg 768w, https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/08\/D4WIQRD2IFEE5NQCM3N6TVLU7U-700x394.jpg 700w, https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/08\/D4WIQRD2IFEE5NQCM3N6TVLU7U-539x303.jpg 539w\" sizes=\"auto, (max-width: 992px) 100vw, 992px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p class=\"paragraph\">Cuatro a\u00f1os despu\u00e9s de Noruega, en 1998, Fabriciano repiti\u00f3 la haza\u00f1a, nuevamente con Walter Sotelo y Humberto G\u00f3mez Lollo. El equipo se completaba con<b>\u00a0<\/b>una mujer,\u00a0<b>Mimo Eidman<\/b>. Esta vez, el escenario fue la ciudad de\u00a0<b>Sapporo, en Jap\u00f3n,<\/b>\u00a0donde tiene lugar una de las competencias internacionales m\u00e1s importantes del mundo. All\u00ed, los 4 chaque\u00f1os convirtieron una monta\u00f1a de nieve en escultura que llamaron \u201cGrito de paz\u201d y con la cual se impusieron en el concurso.<\/p>\n<p class=\"paragraph\">Fabriciano G\u00f3mez\u00a0<b>naci\u00f3 el 27 de junio de 1944<\/b>\u00a0en Resistencia. Estudi\u00f3 en la Academia de Bellas Artes del Chaco de la cual egres\u00f3 en 1968 con el t\u00edtulo de Maestro de Artes Visuales y Profesor de Dibujo.<\/p>\n<p class=\"paragraph\">Vivi\u00f3 varios a\u00f1os en Europa, en Italia, y en Francia<b>. Aunque pudo seguir una carrera brillante en el viejo continente, eligi\u00f3 volver al Chaco en 1982<\/b>, donde se consagr\u00f3 a aplicar lo aprendido y a hacer de Resistencia una ciudad conocida en el mundo como escenario de valiosas experiencias art\u00edsticas. En palabras de Marcelo Nieto,\u00a0<b>\u201cse dir\u00eda que renunci\u00f3 al ego del artista, ya que ten\u00eda sus ateliers en Carrara y Par\u00eds, ten\u00eda propuestas y oportunidades\u00a0<\/b>en Europa donde vivi\u00f3 un lustro, sin embargo el amor al terru\u00f1o lo hizo volver, e incluso dejar a un lado el vestido de artista-individuo para ser productor del gran sue\u00f1o de la Bienal del Chaco\u201d.<\/p>\n<div class=\"visual__image\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10518 alignnone\" src=\"https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/08\/XSVTYGZYNZFXND7P6XDFTLWDVI.jpg\" alt=\"\" width=\"992\" height=\"1488\" srcset=\"https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/08\/XSVTYGZYNZFXND7P6XDFTLWDVI.jpg 992w, https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/08\/XSVTYGZYNZFXND7P6XDFTLWDVI-200x300.jpg 200w, https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/08\/XSVTYGZYNZFXND7P6XDFTLWDVI-683x1024.jpg 683w, https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/08\/XSVTYGZYNZFXND7P6XDFTLWDVI-768x1152.jpg 768w, https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/08\/XSVTYGZYNZFXND7P6XDFTLWDVI-700x1050.jpg 700w\" sizes=\"auto, (max-width: 992px) 100vw, 992px\" \/><\/div>\n<div class=\"visual__image\">&#8220;Caminante&#8221;, obra de Fabriciano G\u00f3mez<\/div>\n<p>&nbsp;<\/p>\n<p class=\"paragraph\">Su etapa fuera del pa\u00eds \u201cfue un tiempo en que recorr\u00eda el mundo compitiendo en concursos de escultura en hielo y nieve, pero\u00a0<b>cuando no estaba ocupado en martillar el hielo que esculp\u00eda, observaba detenidamente los engranajes que mov\u00edan esos eventos art\u00edsticos mundiales<\/b>\u00a0y, de vuelta a casa, dec\u00eda a los suyos, a los periodistas, a los funcionarios: \u2018\u201dAc\u00e1, en Resistencia, tenemos que hacer algo parecido\u2019\u201d.<\/p>\n<p class=\"paragraph\">\u201cComenzar\u00eda una semblanza contando que\u00a0<b>su padre era el sereno de la plaza principal de la ciudad,<\/b>\u00a0donde, a\u00f1os despu\u00e9s, por impulso y gravitaci\u00f3n de Fabriciano, se realizaba el primer concurso de esculturas en madera al aire libre, cuyo derrotero nos trae hoy a la Bienal del Chaco\u201d, dice Nieto.<\/p>\n<p class=\"paragraph\">Aquel primer concurso de esculturas se organiz\u00f3 en 1988. Para ello,\u00a0<b>Fabriciano reuni\u00f3 voluntades y fatig\u00f3 despachos oficiales:\u00a0<\/b>no fue sencillo convencer a todos de que era posible una experiencia de esa clase. Aquel primer certamen fue un gran \u00e9xito: m\u00e1s de 200 mil personas concurrieron para ver a un pu\u00f1ado de escultores trabajar a cielo abierto durante una semana, tallando en madera.<\/p>\n<p class=\"paragraph\">Desde entonces, las bienales fueron creciendo,\u00a0<b>se volvieron internacionales,\u00a0<\/b>la plaza qued\u00f3 chica, y la Fundaci\u00f3n Urunday recibi\u00f3 un predio junto al r\u00edo que hoy es visitado por m\u00e1s de\u00a0<b>medio mill\u00f3n de personas en cada edici\u00f3n de la bienal, como sucedi\u00f3\u00a0<\/b><a href=\"https:\/\/www.infobae.com\/cultura\/2022\/07\/23\/bienal-de-esculturas-del-chaco-claves-y-secretos-de-un-modelo-de-arte-publico-exitoso\/\" target=\"_blank\" rel=\"noopener\"><b>en la que acaba de concluir en Resistencia, el pasado 23 de julio.<\/b><\/a><\/p>\n<div class=\"visual__image\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10516 alignnone\" src=\"https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/08\/MWGUU2WPGFENHEOQ56F2VJTDWQ.jpg\" alt=\"\" width=\"992\" height=\"558\" srcset=\"https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/08\/MWGUU2WPGFENHEOQ56F2VJTDWQ.jpg 992w, https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/08\/MWGUU2WPGFENHEOQ56F2VJTDWQ-300x169.jpg 300w, https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/08\/MWGUU2WPGFENHEOQ56F2VJTDWQ-768x432.jpg 768w, https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/08\/MWGUU2WPGFENHEOQ56F2VJTDWQ-700x394.jpg 700w, https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/08\/MWGUU2WPGFENHEOQ56F2VJTDWQ-539x303.jpg 539w\" sizes=\"auto, (max-width: 992px) 100vw, 992px\" \/><\/div>\n<div class=\"visual__image\">Vista a\u00e9rea de Resistencia desde el r\u00edo. Adelante, el predio donde tiene lugar la Bienal<\/div>\n<p>&nbsp;<\/p>\n<p class=\"paragraph\">\u201cFabriciano esculpi\u00f3 con habilidad\u00a0<b>las duras maderas chaque\u00f1as de nombres misteriosos: it\u00edn, guayac\u00e1n, quebracho, urunday<\/b>. Pero tambi\u00e9n, con igual ductilidad, el\u00a0<b>m\u00e1rmol, el metal, el hielo, la nieve<\/b>\u201d, sigue diciendo Marcelo Nieto. Y aunque considera que \u201cson odiosos los curr\u00edculos\u201d porque \u201ctienen un viso de jactancia\u201d, cree menester \u201cdecir que Fabriciano obtuvo el\u00a0<b>Gran Premio del Sal\u00f3n Nacional en 1977,<\/b>\u00a0represent\u00f3 a la Argentina en la\u00a0<b>Bienal de Venecia de 1980<\/b>\u00a0y trajo al Chaco las medallas de oro de las olimp\u00edadas de Lillehamer, Noruega, y el Gran Premio de Honor de Saporo, Jap\u00f3n\u201d.<\/p>\n<p class=\"paragraph\">Adem\u00e1s, que \u201cfue<b>\u00a0Konex, ciudadano ejemplar, honoris causa de la Universidad del Nordeste\u00a0<\/b>(UNNE), pero dec\u00eda que el reconocimiento m\u00e1s valioso para \u00e9l era la imposici\u00f3n de\u00a0<b>su nombre en una escuela para adultos en los bordes de la ciudad,<\/b>\u00a0elegido por votaci\u00f3n de los alumnos: Escuela n\u00b0 37 Fabriciano G\u00f3mez\u201d<\/p>\n<p class=\"paragraph\">Cinco a\u00f1os antes de su muerte,\u00a0<b>Fabriciano anunci\u00f3 que donaba su casa museo<\/b> a la comunidad. Al comunicarlo, dec\u00eda: \u201cHoy estoy en paz, puedo decir \u2018Resistencia, he cumplido\u2019, a mis padres, que me trajeron al mundo, les puedo decir que he cumplido con su objetivo: ser una buena persona, que tenga c\u00f3digos, que trabaje, que me gane el pan de cada d\u00eda\u201d.<\/p>\n<div class=\"jwplayer-ctn\">\n<div>\n<div id=\"lN0dvVR7\" class=\"jwplayer jw-reset jw-state-idle jw-stretch-uniform jw-flag-aspect-mode jw-floating-dismissible jw-breakpoint-4 jw-flag-user-inactive\" tabindex=\"0\" role=\"application\" aria-label=\"Reproductor de Video\" aria-describedby=\"jw-shortcuts-tooltip-explanation\">\n<div class=\"jw-wrapper jw-reset\">\n<div class=\"jw-controls jw-reset\">\n<div class=\"jw-nextup-container jw-reset\">\n<div class=\"jw-nextup jw-background-color jw-reset\">\n<div class=\"jw-nextup-tooltip jw-reset\">\n<div class=\"jw-nextup-body jw-reset\">\n<div class=\"jw-nextup-title jw-reset-text\" dir=\"auto\"><\/div>\n<div class=\"jw-nextup-duration jw-reset\"><\/div>\n<\/div>\n<\/div>\n<p><iframe loading=\"lazy\" src=\"\/\/content.jwplatform.com\/players\/lN0dvVR7-a9NdgpIU.html\" width=\"640\" height=\"360\" frameborder=\"0\" scrolling=\"auto\"><\/iframe><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>Fabriciano G\u00f3mez habla de la casa museo que dona a la comunidad<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<p class=\"paragraph\">A su casa, que alberga algunas de las m\u00e1s de 4000 esculturas que hizo a lo largo de su vida, la describ\u00eda como \u201cun patrimonio\u201d.\u00a0<b>\u201cEsta casa para m\u00ed es muy m\u00e1gica, porque los veo a mis padres, a mis hermanos, yo fui parido aqu\u00ed,\u00a0<\/b>en esta casa\u2026\u201d, dec\u00eda.<\/p>\n<p class=\"paragraph\">Donaba, dec\u00eda, todo el trabajo que justific\u00f3 su existencia:\u00a0<b>\u201cEn estos 72 a\u00f1os que tengo de vida he justificado mi existencia\u00a0<\/b>y c\u00f3mo no dejarle a la ciudad que me ha dado todo, porque el chaque\u00f1o es tan c\u00e1lido, es tan maravilloso, te permite que las cosas sean f\u00e1ciles\u201d.<\/p>\n<p class=\"paragraph\"><b>Una de esas cosas \u201cf\u00e1ciles\u201d, fue la Bienal, un proyecto en el que al principio pocos cre\u00edan<\/b>. \u201c40 a\u00f1os atr\u00e1s nadie hubiera pensado que a Resistencia iban a venir turistas, nadie, nadie, sin embargo nosotros tuvimos fe\u201d, dec\u00eda Fabriciano.<\/p>\n<p class=\"paragraph\">Ese nosotros eran\u00a0<b>\u00e9l y su grupo de la Fundaci\u00f3n Urunday<\/b>, pero tambi\u00e9n los sucesivos gobiernos que fueron respaldando la iniciativa, porque\u00a0<b>la Bienal ya es una pol\u00edtica que trasciende las distintas administraciones provinciales. Es patrimonio provincial.<\/b><\/p>\n<p>&nbsp;<\/p>\n<p class=\"paragraph\"><b>VIDEO: Fabriciano habla de c\u00f3mo se gest\u00f3 la Bienal de Esculturas del Chaco<\/b><\/p>\n<div class=\"jwplayer-ctn\">\n<div>\n<div id=\"6R8sHCCH\" class=\"jwplayer jw-reset jw-state-idle jw-stretch-uniform jw-flag-aspect-mode jw-floating-dismissible jw-breakpoint-4 jw-flag-user-inactive\" tabindex=\"0\" role=\"application\" aria-label=\"Reproductor de Video\" aria-describedby=\"jw-shortcuts-tooltip-explanation\">\n<div class=\"jw-wrapper jw-reset\">\n<div class=\"jw-controls jw-reset\">\n<div class=\"jw-nextup-container jw-reset\">\n<div class=\"jw-nextup jw-background-color jw-reset jw-nextup-thumbnail-visible\">\n<p><iframe loading=\"lazy\" src=\"\/\/content.jwplatform.com\/players\/6R8sHCCH-a9NdgpIU.html\" width=\"640\" height=\"360\" frameborder=\"0\" scrolling=\"auto\"><\/iframe><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>Fabriciano G\u00f3mez y la Bienal de Esculturas<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<p class=\"paragraph\">\u201cY pas\u00f3 el tiempo, pasaron escultores, pasaron miles y miles de personas, sorprendidas\u2026 -evocaba Fabriciano en una entrevista- Los chicos hablandole al (escultor) chino o al ruso, y como no se entend\u00edan, les hac\u00edan dibujitos en un papel y se pon\u00edan a expresarse\u2026\u201d<\/p>\n<p class=\"paragraph\"><mark class=\"hl_yellow\">\u201cResistencia tiene magia -conclu\u00eda-.\u00a0<b>Los que estamos trabajando para hacer del arte un bien de todos<\/b>\u00a0hemos comprendido y tomado conciencia de que esa luz que es forma no qued\u00f3 solamente en nuestras manos o en nuestro interior, no, tuvimos la capacidad y la posibilidad de dar a nuestros semejante\u201d.<\/mark><\/p>\n<p class=\"paragraph\">Ten\u00eda\u00a0<b>un decir po\u00e9tico, que justifica llamar a su obra \u201cpoes\u00eda volum\u00e9trica\u201d<\/b>, como dice el guion del video que presenta su casa museo.<\/p>\n<p class=\"paragraph\">\u201cEra<b>\u00a0un artista que vend\u00eda su obra espl\u00e9ndidamente\u00a0<\/b>y que nunca contradec\u00eda al hombre del llano, al origen humilde. Jam\u00e1s traicion\u00f3 sus esencias\u201d, afirma Nieto.<\/p>\n<p class=\"paragraph\"><mark class=\"hl_yellow\">Y ante la pregunta sobre su popularidad, dice: \u201cS\u00ed,\u00a0<b>lo re-quer\u00eda todo el mundo<\/b>\u2026 Y una vuelta de tuerca m\u00e1s: al gran artista, y humilde hombre, sumale su gesti\u00f3n permanente, su persuasi\u00f3n \u2013al poder y al que estuviera al lado- para hacer de Resistencia\u00a0<b>una ciudad embellecida por esculturas<\/b>\u00a0y con\u00a0<b>un pueblo sensible al arte.\u00a0<\/b>\u2018Fabri\u2019 no es s\u00f3lo la Bienal, sino parques, plazas, un plan de plantaci\u00f3n de esculturas que se extiende hacia las rutas y entra hacia los barrios, concursos o encuentros de escultura replicados en el interior, como el de Castelli o el de Quitilipi, o la plantilla de la Bienal del Chaco entregada para ser calcada en otros lugares del pa\u00eds y de Latinoam\u00e9rica\u2026\u201d<\/mark><\/p>\n<div class=\"visual__image\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10517 alignnone\" src=\"https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/08\/NBMQZJ6G6NCDFOU6QBJFWGWGCM.jpg\" alt=\"\" width=\"992\" height=\"1488\" srcset=\"https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/08\/NBMQZJ6G6NCDFOU6QBJFWGWGCM.jpg 992w, https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/08\/NBMQZJ6G6NCDFOU6QBJFWGWGCM-200x300.jpg 200w, https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/08\/NBMQZJ6G6NCDFOU6QBJFWGWGCM-683x1024.jpg 683w, https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/08\/NBMQZJ6G6NCDFOU6QBJFWGWGCM-768x1152.jpg 768w, https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/08\/NBMQZJ6G6NCDFOU6QBJFWGWGCM-700x1050.jpg 700w\" sizes=\"auto, (max-width: 992px) 100vw, 992px\" \/><\/div>\n<div class=\"visual__image\">En el jard\u00edn de su casa &#8211; museo, donada a la comunidad<\/div>\n<p>&nbsp;<\/p>\n<p class=\"paragraph\">Esa doble condici\u00f3n, de artista y organizador, eso que hoy se suele llamar<b>\u00a0\u201cgestor cultural\u201d.\u00a0<\/b>\u201cEs una forma ruda de definirlo, pero es justamente eso: trabajar, realizar ideas, generar una industria cultural, hacer redes con los dem\u00e1s haceres y saberes,\u00a0<b>estimular la vida de esos que miran el surco para sobrevivir y no las estrellas\u201d,<\/b>\u00a0dice Nieto.<\/p>\n<p class=\"paragraph\">\u201cCon la escultura<b>\u00a0hizo docencia, militancia\u00a0<\/b>-describe-. Una cosa es golpear puertas para pedir un pedazo de pan, eso no es gesti\u00f3n, es supervivencia, es instinto; golpear puertas para vender un sue\u00f1o, ah\u00ed s\u00ed encuentro la gesti\u00f3n cultural. Y las aptitudes de mago\u201d.<\/p>\n<p class=\"paragraph\">Adem\u00e1s de su casa museo, la Bienal del Chaco es el gran legado del escultor chaque\u00f1o.\u00a0<b>\u201cLa relojer\u00eda de esta Bienal fue dise\u00f1ada por Fabriciano y la Fundaci\u00f3n Urunday<\/b>\u00a0\u2013el grupo de amigos que lo acompa\u00f1\u00f3 siempre- . Y sus retru\u00e9canos virtuosos son admirables: cada dos a\u00f1os, los escultores llegan al Chaco para competir, elegidos por sus propuestas, s\u00ed, y por sus firmas porque\u00a0<b>esas obras que vienen a esculpir, pasan al espacio p\u00fablico embelleci\u00e9ndolo,<\/b>\u00a0pero adem\u00e1s, agregan piezas peri\u00f3dicamente al importante museo al aire libre que es Resistencia, con firmas de la escultura contempor\u00e1nea\u201d<\/p>\n<p class=\"paragraph\">Y hay<b>\u00a0una huella cultural dejada por esta gran creaci\u00f3n<\/b>\u00a0que son las bienales y es la formaci\u00f3n de\u00a0<b>un p\u00fablico apasionado, instruido, comprometido y orgulloso de su patrimonio.<\/b><\/p>\n<div class=\"visual__image\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10513 alignnone\" src=\"https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/08\/75BPY34435F2LIYZKTMRHLPYCM.jpg\" alt=\"\" width=\"992\" height=\"661\" srcset=\"https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/08\/75BPY34435F2LIYZKTMRHLPYCM.jpg 992w, https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/08\/75BPY34435F2LIYZKTMRHLPYCM-300x200.jpg 300w, https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/08\/75BPY34435F2LIYZKTMRHLPYCM-768x512.jpg 768w, https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/08\/75BPY34435F2LIYZKTMRHLPYCM-391x260.jpg 391w, https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/08\/75BPY34435F2LIYZKTMRHLPYCM-700x466.jpg 700w\" sizes=\"auto, (max-width: 992px) 100vw, 992px\" \/><\/div>\n<div class=\"visual__image\">Fabriciano G\u00f3mez en la Bienal<\/div>\n<p>&nbsp;<\/p>\n<p class=\"paragraph\">\u201cEl resistenciano -dice Nieto-, habituado a visitar la Bienal,\u00a0<b>labra empat\u00edas con los artistas, y advierte lo sofisticado del trabajo, la laboriosidad\u00a0<\/b>y sentimiento que imprimen en la obra, la maestr\u00eda de sus t\u00e9cnicas y el manejo profesional de las herramientas. Eso hace que el ciudadano valore a la escultura no solo por la belleza o el mensaje \u2013los dos grandes dones del arte- sino porque conoci\u00f3 al seguramente ex\u00f3tico escultor, acompa\u00f1\u00f3 la g\u00e9nesis de la obra y, con naturalidad, asume una guarda, una delicadeza de cuidado,\u00a0<b>aunque tomen mates los enamorados en los pedestales, o jueguen los ni\u00f1os con interacci\u00f3n de escultura\u201d.<\/b><\/p>\n<p class=\"paragraph\">Finalmente, Marcelo Nieto describe la personalidad de Fabriciano:\u00a0<mark class=\"hl_yellow\">\u201cEra un maestro de esos con muchas encarnaciones encima.\u00a0<b>Ten\u00eda mucho de ind\u00edgena en sus silencios, sus miradas, sus consejos,<\/b>\u00a0<b>lanzados con una sencillez que los hac\u00eda m\u00e1s profundos;\u00a0<\/b>era una m\u00e1quina de so\u00f1ar pero de realizar materialmente esos sue\u00f1os y eso era lo impresionante. Fabriciano ten\u00eda la humildad del despose\u00eddo, la fe de quien venera a su madre, el car\u00e1cter de quien lleva el pan a la mesa, la generosidad de quien ha cosechado amigos, la obstinaci\u00f3n de quien ha jurado, el adorno del humor, la simpleza del honesto\u2026Era el l\u00edder sin dejar el vestido del soldado\u201d.<\/mark><\/p>\n<p class=\"paragraph\">La escultura le hab\u00eda dejado\u00a0<b>huellas en el cuerpo<\/b>. Ten\u00eda da\u00f1ados los o\u00eddos por no haber usado protecci\u00f3n en sus primeros trabajos con herramientas ruidosas. Fabriciano dec\u00eda que\u00a0<b>nunca se hab\u00eda hecho un estudio para ver cu\u00e1nto m\u00e1rmol ten\u00eda en los pulmones por haber aspirado mucho polvillo<\/b>. Contaba que su m\u00e9dico le ped\u00eda que abandonara los concursos en el hielo porque eran muy gravosos para la salud.<\/p>\n<p class=\"paragraph\">\u201cLas obras de Fabriciano, formas espaciales, de elegancia sutil de nudos y curvas y ejes invisibles y de alg\u00fan gracioso oblicuo, masas no figurativas, impolutas, tan minimales\u2026\u00a0<b>se me ocurre que as\u00ed era su mente<\/b>\u2026\u201d, dice.<\/p>\n<div class=\"visual__image\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10515 alignnone\" src=\"https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/08\/EATQLOVVBRBMLI7M3GECIIPXEY.jpg\" alt=\"\" width=\"992\" height=\"992\" srcset=\"https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/08\/EATQLOVVBRBMLI7M3GECIIPXEY.jpg 992w, https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/08\/EATQLOVVBRBMLI7M3GECIIPXEY-300x300.jpg 300w, https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/08\/EATQLOVVBRBMLI7M3GECIIPXEY-150x150.jpg 150w, https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/08\/EATQLOVVBRBMLI7M3GECIIPXEY-768x768.jpg 768w, https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/08\/EATQLOVVBRBMLI7M3GECIIPXEY-570x570.jpg 570w, https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/08\/EATQLOVVBRBMLI7M3GECIIPXEY-500x500.jpg 500w, https:\/\/www.bienaldelchaco.org\/2024\/wp-content\/uploads\/2022\/08\/EATQLOVVBRBMLI7M3GECIIPXEY-700x700.jpg 700w\" sizes=\"auto, (max-width: 992px) 100vw, 992px\" \/><\/div>\n<div class=\"visual__image\">Escultura en bronce<\/div>\n<p>&nbsp;<\/p>\n<p class=\"paragraph\">En una nota que titul\u00f3 \u201cFabriciano, pan de la escultura chaque\u00f1a\u201d, Nieto lo defini\u00f3 as\u00ed:\u00a0<b>\u201cMaestro sabio y aprendiz d\u00f3cil. Hombre de fe. La humildad es estandarte, el trabajo una m\u00edstica; insobornable el amor a su tierra<\/b>\u201d. Esa vez, Nieto le hab\u00eda preguntado por su muerte, y la respuesta fue:\u00a0<b>\u201cNo hay temor a la muerte. S\u00ed tristeza por la muerte innecesaria,\u00a0<\/b>como la de un muchacho que muere en la guerra\u2026 El hombre no vino a la tierra para morir en una guerra. Una vez quise morir. De dolor, y mirando hacia adentro sent\u00ed que se hab\u00edan cumplido mis objetivos, todos. Si me pregunt\u00e1s qu\u00e9 dej\u00e9 de hacer, dudo, debiera pensarlo bien.\u00a0<b>Logr\u00e9 todo y mucho m\u00e1s de lo esperado\u201d.<\/b><\/p>\n<p class=\"paragraph\">En aquel anuncio de la donaci\u00f3n, dec\u00eda Fabriciano, a modo de balance:\u00a0<b>\u201cMe voy, me voy como vine al mundo, me voy sin nada, liviano, pero fui un afortunado en la vida,<\/b>\u00a0me voy con esa carga, pero adentro\u201d,<\/p>\n<p class=\"paragraph\">Sobre su muerte inesperada, Nieto dice: \u201cFall\u00f3 su coraz\u00f3n. Por eso muri\u00f3. Me gusta pensar que aquella madrugada esos duendes del bosque chaque\u00f1o que viven dentro de los \u00e1rboles,\u00a0<b>salieron a despedir la canoa de urunday que llevaba su alma qui\u00e9n sabe a d\u00f3nde\u2026\u201d<\/b><\/p>\n<p class=\"paragraph\">Y en cuanto al futuro de la Bienal sin Fabriciano, responde: \u201cComo era muy proyectual, como la Fundaci\u00f3n Urunday ven\u00eda trabajando desde a\u00f1os, el futuro, la heredad, los continuadores, su muerte m\u00e1s que el impacto emocional no da\u00f1\u00f3 en nada este gran proyecto que es la Bienal.\u201d<\/p>\n<p>&nbsp;<\/p>\n<p class=\"paragraph\"><b>VIDEO: \u201cMe voy como vine&#8230;\u201d<\/b><\/p>\n<div class=\"jwplayer-ctn\">\n<div>\n<div id=\"5KyRlitT\" class=\"jwplayer jw-reset jw-state-idle jw-stretch-uniform jw-flag-aspect-mode jw-floating-dismissible jw-breakpoint-4 jw-flag-user-inactive\" tabindex=\"0\" role=\"application\" aria-label=\"Reproductor de Video\" aria-describedby=\"jw-shortcuts-tooltip-explanation\">\n<div class=\"jw-wrapper jw-reset\">\n<div class=\"jw-controls jw-reset\">\n<div class=\"jw-nextup-container jw-reset\">\n<div class=\"jw-nextup jw-background-color jw-reset\">\n<p><iframe loading=\"lazy\" src=\"\/\/content.jwplatform.com\/players\/5KyRlitT-a9NdgpIU.html\" width=\"640\" height=\"360\" frameborder=\"0\" scrolling=\"auto\"><\/iframe><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p class=\"paragraph\">As\u00ed lo confirm\u00f3 la \u00faltima edici\u00f3n que concluy\u00f3 el 23 de julio pasado. Y,\u00a0<b>en simult\u00e1neo, la presentaci\u00f3n del pr\u00f3ximo encuentro, la Bienal 2024.<\/b><\/p>\n<p class=\"paragraph\">Mimo Eidman, integrante de\u00a0<b>ese \u201cgrupo de locos\u201d, como llamaba Fabriciano a sus amigos de la Fundaci\u00f3n Urunday<\/b>, escribi\u00f3, cuando el escultor todav\u00eda estaba vivo, esta semblanza en su p\u00e1gina oficial: \u201cFabriciano G\u00f3mez es\u00a0<b>uno de esos seres en los que Dios reuni\u00f3 una serie de virtudes con una combinaci\u00f3n privilegiada<\/b>\u00a0y que dio como resultante un personaje marcadamente distinto a los dem\u00e1s: supercreativo, solidario, generoso, trabajador incansable, perseverante, con objetivos bien claros desde muy joven y con un sentido alerta para detectar las oportunidades que se le presentan en la vida y no dejarlas pasar.\u00a0<b>Es paternalista, sobreprotector, tiene un alto grado de optimismo y pasi\u00f3n en todo lo que emprende,\u00a0<\/b>tanto que no se permite la posibilidad de lluvias aunque est\u00e9n pronosticadas con un alerta meteorol\u00f3gico.\u00a0<b>Esto habla de su fe y de su inconsciencia, cualidades que lo han llevado a lograr tempranamente casi todos sus objetivos\u201d.<\/b><\/p>\n<p>&nbsp;<\/p>\n<p class=\"paragraph\"><b>VIDEO: El anuncio de la Bienal 2024<\/b><\/p>\n<div class=\"jwplayer-ctn\">\n<div>\n<div id=\"AsH7wxWb\" class=\"jwplayer jw-reset jw-state-idle jw-stretch-uniform jw-flag-aspect-mode jw-floating-dismissible jw-breakpoint-4 jw-flag-user-inactive\" tabindex=\"0\" role=\"application\" aria-label=\"Reproductor de Video\" aria-describedby=\"jw-shortcuts-tooltip-explanation\">\n<div class=\"jw-wrapper jw-reset\">\n<div class=\"jw-controls jw-reset\">\n<div class=\"jw-nextup-container jw-reset\">\n<div class=\"jw-nextup jw-background-color jw-reset jw-nextup-thumbnail-visible\">\n<p><iframe loading=\"lazy\" src=\"\/\/content.jwplatform.com\/players\/AsH7wxWb-a9NdgpIU.html\" width=\"640\" height=\"360\" frameborder=\"0\" scrolling=\"auto\"><\/iframe><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>Bienal Chaco 2024 Anuncio<\/p>\n<\/div>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221;][vc_column][vc_empty_space][vc_column_text]Fuente:\u00a0 <a href=\"https:\/\/www.infobae.com\/cultura\/2022\/08\/02\/de-hijo-de-sereno-de-plaza-a-escultor-llevado-en-andas-por-la-gente-vida-y-obra-del-chaqueno-fabriciano-gomez\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.infobae.com\/cultura\/2022\/08\/02\/de-hijo-de-sereno-de-plaza-a-escultor-llevado-en-andas-por-la-gente-vida-y-obra-del-chaqueno-fabriciano-gomez\/<\/a>[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>El creador de la Bienal Internacional de Escultura del Chaco muri\u00f3 el 8 de septiembre de 2021, a los 77 a\u00f1os. Poco antes, dec\u00eda: \u201cMe voy como vine, sin nada, liviano, pero con la carga interior de haber sido un afortunado en la vida y&#8230;<\/p>\n","protected":false},"author":3,"featured_media":10519,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-10512","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novedades"],"_links":{"self":[{"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/posts\/10512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/comments?post=10512"}],"version-history":[{"count":5,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/posts\/10512\/revisions"}],"predecessor-version":[{"id":10524,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/posts\/10512\/revisions\/10524"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/media\/10519"}],"wp:attachment":[{"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/media?parent=10512"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/categories?post=10512"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/tags?post=10512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}