{"id":12920,"date":"2024-06-12T19:41:11","date_gmt":"2024-06-12T22:41:11","guid":{"rendered":"https:\/\/www.bienaldelchaco.org\/2024\/?p=12920"},"modified":"2024-06-12T19:41:11","modified_gmt":"2024-06-12T22:41:11","slug":"jose-eidman-con-la-bienal-la-escultura-se-volvio-una-accion-artistica","status":"publish","type":"post","link":"https:\/\/www.bienaldelchaco.org\/2024\/jose-eidman-con-la-bienal-la-escultura-se-volvio-una-accion-artistica\/","title":{"rendered":"Jos\u00e9 Eidman: &#8220;Con la Bienal la escultura se volvi\u00f3 una acci\u00f3n art\u00edstica&#8221;"},"content":{"rendered":"<p class=\"td-subTitle\">El presidente de la Fundaci\u00f3n Urunday, entrevistado por momarandu.com, destac\u00f3 la evoluci\u00f3n del evento en sus m\u00e1s de 30 a\u00f1os de existencia, pasando de anual a uno bienal, cambiando los materiales utilizados por los escultores, desde la madera local hasta piedra, m\u00e1rmol y metal, y remarc\u00f3 que debido a ello, Resistencia pudo enriquecerse culturalmente aprendiendo de maestros nacionales e internacionales hasta convertirse en uno de los museos a cielo abierto m\u00e1s importantes del mundo.<\/p>\n<p><!--more-->[vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221;][vc_column][vc_column_text]\n<div class=\"row\">\n<div id=\"conte\" class=\"span6 base\">\n<p>Eidman expres\u00f3 que en la Bienal no solo se exhiben esculturas, sino que tambi\u00e9n se incluyen otras disciplinas art\u00edsticas como danza, teatro, m\u00fasica y congresos de arte.<\/p>\n<p>Subray\u00f3 que el evento es gratuito y atrae a visitantes de distintas regiones, su trascendencia para generar un impacto positivo en la econom\u00eda local y transformar a la ciudad en una plataforma de desarrollo cultural sustentable que fomenta la participaci\u00f3n y el aprendizaje art\u00edstico.<\/p>\n<p><em><strong>La Fundaci\u00f3n Urunday, hace mucho tiempo, es organizadora de la Bienal, que ya tiene fecha, en los tres d\u00edas del mes de julio. Comenz\u00f3 en la d\u00e9cada de los 80, en la Plaza 25 de Mayo, fue creciendo y ahora es un polo de atracci\u00f3n cultural y tur\u00edstico para el Chaco.<\/strong><\/em><br \/>\n&#8211; S\u00ed, la verdad es que, como lo dec\u00eda reci\u00e9n, esto es un acontecimiento art\u00edstico que surgi\u00f3 en el a\u00f1o 1988, poquitos a\u00f1os despu\u00e9s de que Fabriciano G\u00f3mez, este escultor chaque\u00f1o consagrado en el mundo, vino con una loqu\u00edsima idea que fue llevar a 35 escultores de la Argentina a trabajar en la plaza central de la ciudad. Un acontecimiento in\u00e9dito en Am\u00e9rica y, de repente, la cl\u00e1sica del arte, que es la escultura, se volvi\u00f3 una acci\u00f3n art\u00edstica, una intervenci\u00f3n del espacio p\u00fablico, donde fue realmente algo muy novedoso y la comunidad de Resistencia autom\u00e1ticamente se volc\u00f3 a la plaza. Por ah\u00ed pas\u00e1bamos todos: los que iban al banco, los que iban al caf\u00e9, los que iban a trabajar, los que \u00edbamos a la facultad.<\/p>\n<p><em><strong>Nos qued\u00e1bamos a charlar con los escultores y nos mostraban la t\u00e9cnica. Record\u00e1bamos tambi\u00e9n que a\u00f1o a a\u00f1o el material utilizado era distinto, y eso nos permit\u00eda, porque al principio fue, \u00bfse acuerda que fue anual? Despu\u00e9s se pas\u00f3 a hacer bienal.<\/strong><\/em><br \/>\n&#8211; Exactamente, en el 98 se volvi\u00f3 bienal y al principio se trabajaba con madera dura de la zona y con el tiempo se volvi\u00f3 bienal. Con el objetivo de seguir alimentando ese patrimonio escult\u00f3rico que hay en la ciudad, en las veredas de la ciudad, se cambiaron los materiales. La gente pod\u00eda pasar y ver a estos escultores trabajando a veces la piedra, el m\u00e1rmol, a veces el metal. Y as\u00ed, bueno, de alguna manera el ciudadano se fue enriqueciendo. Nosotros estuvimos aprendiendo de estos grandes maestros de la escultura que empezaron siendo nacionales y con el correr de los a\u00f1os&#8230; Hoy, ya 36 a\u00f1os de aquel primer concurso, ya con formato bienal, se ha consolidado en la escena internacional de la escultura como uno de los cert\u00e1menes a cielo abierto m\u00e1s importantes del mundo.<\/p>\n<p><em><strong>La visi\u00f3n de la sociedad fue cambiando y lo que antes no estaba tan permitido o era ocultado, fue a principios del 2000 tomando una nueva idiosincrasia.<\/strong><\/em><br \/>\n&#8211; S\u00ed, totalmente. Hasta el 2016, hasta el 2018, inclusive, cada bienal ten\u00eda un tema que se propon\u00eda para inspirar a los diferentes artistas del mundo y artistas locales. A partir del 2020, ya Fabriciano todav\u00eda viv\u00eda, decidi\u00f3 un poco soltar eso de establecer tem\u00e1ticas y dejar a los artistas crear con total libertad, sin ning\u00fan tema que los inspire. As\u00ed que, en esta ocasi\u00f3n, ya con una tem\u00e1tica libre, pero sin duda atravesado por esto que hoy, de alguna manera, nos toca a todos, que es la tecnolog\u00eda y la inteligencia artificial, gran parte de los contenidos de esta bienal, que no solo es de escultura, porque claramente ese certamen tradicional, hoy, ya en formato bienal y con car\u00e1cter internacional, re\u00fane a 10 escultores del mundo, que para esta edici\u00f3n han sido seleccionados entre m\u00e1s de 157 postulantes de 55 pa\u00edses. Esta gran actividad escult\u00f3rica de conocimiento internacional se completa con casi todas las dem\u00e1s disciplinas art\u00edsticas, porque durante esa semana del 13 al 21 de julio, este predio de 10 hect\u00e1reas tendr\u00e1 danza, teatro, m\u00fasica, congreso internacional de artes, un festival filarm\u00f3nico. En esta gran manifestaci\u00f3n de arte contempor\u00e1neo, no solo conviven los artistas consagrados, sino tambi\u00e9n los artistas en la gente del territorio de la disciplina. Entonces, es realmente muy interesante el enriquecimiento y de alguna manera c\u00f3mo estos saberes se transfieren y los artistas los cuales tambi\u00e9n encuentran en esta disciplina alguna oportunidad para visibilizar su arte, para perfeccionar su arte, y de alguna manera para empezar a transitar su trayectoria art\u00edstica y dejar a sus futuros disc\u00edpulos.<\/p>\n<p><em><strong>Uno entiende que la atracci\u00f3n fundamental son los artistas internacionales. Recuerdo un evento, cuando la Camerata Bariloche se pudo disfrutar en el Domo.<\/strong><\/em><br \/>\n&#8211; S\u00ed, fant\u00e1stico. Eso es lo que se da en esa semana, que adem\u00e1s de acceso gratuito para todo el mundo, combina la posibilidad de disfrutar en familia de casi todas las disciplinas art\u00edsticas. Y como dec\u00edas vos, el artista local, tambi\u00e9n el artista convocado, un escenario que funciona de manera sincronizada, el nuevo escenario, un gran escenario en la pista del atletismo, otro en el anfiteatro donde est\u00e1 la banda de emergentes. Realmente, una actividad que pensando en coincidir con la primera semana de la reuni\u00f3n de invierno, se vuelve un destino ligado para todos los que estamos en la regi\u00f3n, para los chaque\u00f1os, los correntinos, los formose\u00f1os. Un destino, una cita obligada es venir a los \u00faltimos d\u00edas a disfrutar de la arena y tener esta oferta art\u00edstica y cultural tan ensanchada, m\u00e1s a esas personas argentinas, m\u00e1s a esas personas de pueblos originarios. Realmente, una fiesta de verdad y de cultura que se ha transformado en una plataforma de desarrollo cultural sustentable, porque esto genera actividad y hace un impacto p\u00fablico, tambi\u00e9n un impacto social en nuestra comunidad. Porque para invierno, cada viernes, cada julio, cada noviembre, no solo a las disciplinas art\u00edsticas, sino tambi\u00e9n en Corrientes, a las oficinas ciudadanas, a los restaurantes que trabajan todos los d\u00edas. Realmente es una muestra de que el arte no solo es una expresi\u00f3n est\u00e9tica, sino que tambi\u00e9n es un agente transformador muy poderoso para mejorar la realidad econ\u00f3mica y social de nuestra comunidad.<\/p>\n<\/div>\n<\/div>\n[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221;][vc_column][vc_empty_space][vc_column_text]Fuente:\u00a0 <a href=\"https:\/\/www.momarandu.com\/notix\/noticia\/48905_jos-eidman-con-la-bienal-la-escultura-se-volvi-una-accin-artstica.htm\" target=\"_blank\" rel=\"noopener\">https:\/\/www.momarandu.com\/notix\/noticia\/48905_jos-eidman-con-la-bienal-la-escultura-se-volvi-una-accin-artstica.htm<\/a>[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>El presidente de la Fundaci\u00f3n Urunday, entrevistado por momarandu.com, destac\u00f3 la evoluci\u00f3n del evento en sus m\u00e1s de 30 a\u00f1os de existencia, pasando de anual a uno bienal, cambiando los materiales utilizados por los escultores, desde la madera local hasta piedra, m\u00e1rmol y metal, y&#8230;<\/p>\n","protected":false},"author":3,"featured_media":12918,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-12920","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novedades"],"_links":{"self":[{"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/posts\/12920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/comments?post=12920"}],"version-history":[{"count":1,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/posts\/12920\/revisions"}],"predecessor-version":[{"id":12921,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/posts\/12920\/revisions\/12921"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/media\/12918"}],"wp:attachment":[{"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/media?parent=12920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/categories?post=12920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/tags?post=12920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}