{"id":7765,"date":"2020-03-12T17:24:11","date_gmt":"2020-03-12T20:24:11","guid":{"rendered":"https:\/\/www.bienaldelchaco.org\/2024\/?p=7765"},"modified":"2020-03-12T17:24:11","modified_gmt":"2020-03-12T20:24:11","slug":"se-comienza-a-palpitar-la-bienal-de-escultura-2020-el-martes-se-hara-el-lanzamiento-oficial","status":"publish","type":"post","link":"https:\/\/www.bienaldelchaco.org\/2024\/se-comienza-a-palpitar-la-bienal-de-escultura-2020-el-martes-se-hara-el-lanzamiento-oficial\/","title":{"rendered":"Se comienza a palpitar la Bienal de Escultura 2020: el martes se har\u00e1 el lanzamiento oficial"},"content":{"rendered":"<p class=\"td-post-sub-title\">El Comit\u00e9 Organizador, integrado por el Gobierno del Chaco y la Fundaci\u00f3n Urunday, presentar\u00e1 oficialmente la Bienal Internacional de Escultura 2020. El lanzamiento se realizar\u00e1 el 17 de marzo a las 21 en el MusEUM, en avenida de Los Inmigrantes 1001, en Resistencia. Participar\u00e1n el presidente de la Fundaci\u00f3n, Fabriciano G\u00f3mez y el gobernador, Jorge Capitanich.<\/p>\n<p><!--more--><\/p>\n<div class=\"td-module-meta-info\">\n<p>Nuevamente, grandes escultores del mundo en escena y en acci\u00f3n, trabajar\u00e1n a cielo abierto y en p\u00fablico, esculpiendo piezas que tienen por destino las veredas de Resistencia.<\/p>\n<p>Este a\u00f1o, la Bienal se desarrollar\u00e1 del 11 al 18 de julio en el predio de las Bienales. Del concurso principal participar\u00e1n 10 escultores de distintos puntos del planeta quienes esculpir\u00e1n una obra original en m\u00e1rmol travertino. La entrada ser\u00e1 como siempre abierta y gratuita.<\/p>\n<p>Adem\u00e1s de esta competencia, habr\u00e1 una nutrida agenda de actividades entre las que se cuentan: el Encuentro de Escultores Invitados; el concurso de escultura para estudiantes de Artes; el Congreso Internacional de Artes; el Seminario de Arte, Derecho, Patrimonio y Urbanismo y el Congreso Internacional de Derecho del Arte.<\/p>\n<p>Tambi\u00e9n se realizar\u00e1 el Festival Filarm\u00f3nico Juvenil, el Encuentro de Maestros Artesanos Argentinos y el Encuentro de Artesanos de Pueblos Originarios.<\/p>\n<p>Complementariamente, habr\u00e1 otras actividades y expresiones plurales del arte y la cultura como lo son las Artes Esc\u00e9nicas y Combinadas; cursos, talleres y conferencias magistrales; muestras individuales y colectivas; feria de artesan\u00eda y dise\u00f1o y gastronom\u00eda regional, entre otras.<\/p>\n<p>Cinco centenares de artistas pasaron por el Chaco en estos 32 a\u00f1os de concursos. Sus obras engrosaron un patrimonio art\u00edstico p\u00fablico que hoy cuenta con m\u00e1s de 650 esculturas, haciendo de Resistencia un museo al aire libre \u00fanico en el mundo.<\/p>\n<p>Las obras emplazadas en la capital chaque\u00f1a en su gran mayor\u00eda son el resultado de los concursos y Bienales Internacionales realizadas desde 1988.<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<p>Fuente:<a href=\"http:\/\/www.chacodiapordia.com\/2020\/03\/12\/se-comienza-a-palpitar-la-bienal-de-escultura-2020-el-martes-se-hara-el-lanzamiento-oficial\/\" target=\"_blank\" rel=\"noopener\">\u00a0http:\/\/www.chacodiapordia.com\/2020\/03\/12\/se-comienza-a-palpitar-la-bienal-de-escultura-2020-el-martes-se-hara-el-lanzamiento-oficial\/<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Comit\u00e9 Organizador, integrado por el Gobierno del Chaco y la Fundaci\u00f3n Urunday, presentar\u00e1 oficialmente la Bienal Internacional de Escultura 2020. El lanzamiento se realizar\u00e1 el 17 de marzo a las 21 en el MusEUM, en avenida de Los Inmigrantes 1001, en Resistencia. Participar\u00e1n el&#8230;<\/p>\n","protected":false},"author":3,"featured_media":7766,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-7765","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novedades"],"_links":{"self":[{"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/posts\/7765","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/comments?post=7765"}],"version-history":[{"count":1,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/posts\/7765\/revisions"}],"predecessor-version":[{"id":7767,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/posts\/7765\/revisions\/7767"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/media\/7766"}],"wp:attachment":[{"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/media?parent=7765"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/categories?post=7765"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/tags?post=7765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}