{"id":8619,"date":"2022-02-25T11:11:48","date_gmt":"2022-02-25T14:11:48","guid":{"rendered":"https:\/\/www.bienaldelchaco.org\/2024\/?p=8619"},"modified":"2022-03-03T13:28:47","modified_gmt":"2022-03-03T16:28:47","slug":"concurso-de-cuentos-y-poesias-sobre-esculturas-del-mundo","status":"publish","type":"post","link":"https:\/\/www.bienaldelchaco.org\/2024\/concurso-de-cuentos-y-poesias-sobre-esculturas-del-mundo\/","title":{"rendered":"Concurso de cuentos y poes\u00edas sobre esculturas del mundo"},"content":{"rendered":"<p>Este jueves 24 de febrero, en la Fundaci\u00f3n Urunday, se realiz\u00f3 el lanzamiento de una nueva edici\u00f3n del Concurso Internacional &#8220;Premio Provincia del Chaco&#8221; de cuentos y poes\u00edas sobre una escultura.<\/p>\n<p><!--more-->[vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221;][vc_column][vc_column_text]El certamen literario est\u00e1 organizado por Sociedad Argentina de Escritores Filial Chaco, Fundaci\u00f3n Urunday, Instituto de Cultura de la Provincia del Chaco, Editorial Contexto y Facultad de Artes, Dise\u00f1o y Ciencias de la Cultura de la Universidad Nacional del Nordeste.<\/p>\n<p>La singularidad del concurso reside en que tanto la poes\u00eda como el cuento, deben hacer referencia a una escultura real emplazada en cualquier lugar del mundo.<\/p>\n<p>Cabe recordar que el primer concurso en el a\u00f1o 2019, tuvo convocatoria nacional y se dio en el marco de los festejos de los 30 a\u00f1os de la Fundaci\u00f3n Urunday . Pero ya en el 2020 adquiri\u00f3 formato internacional.<\/p>\n<p>El presidente de la Fundaci\u00f3n Urunday Josese Eidman; destac\u00f3 que la continuidad de un proyecto siempre es un buen indicio: Se\u00f1al de que el camino es firme y conduce a buen puerto.<\/p>\n<p>Nos complace presentar una nueva edici\u00f3n del concurso Internacional de cuentos y poes\u00edas sobre las esculturas.<\/p>\n<p>Con el sentimiento de que a trav\u00e9s de la escultura se consolida una identidad chaque\u00f1a exportable al mundo; hoy asistimos a la tercera edici\u00f3n del Premio \u201cProvincia del Chaco\u201d que se ha fortalecido en convocatoria y extensi\u00f3n: el certamen de car\u00e1cter nacional se abri\u00f3 al mundo de habla hispana.<\/p>\n<p>Tambi\u00e9n me parece valioso destacar algo que creo, es, una virtud resistenciana: esa facilidad, esa espontaneidad de aunar fuerzas, construir juntos y vincularnos en el hacer.<\/p>\n<p>Que esta nueva edici\u00f3n nos lleve, otra vez, a buen puerto, aquel puerto donde las esculturas nos cuentan historias maravillosas.<\/p>\n<p>Por su parte el Pte. de la Sade filial Chaco, Fabio Echarri record\u00f3; &#8220;podr\u00e1n participar personas mayores de 16 a\u00f1os, de cualquier nacionalidad.<\/p>\n<p>La tem\u00e1tica de las poes\u00edas o cuentos presentados es libre, pero debe indefectiblemente estar referida o mencionar una escultura o monumento escult\u00f3rico espec\u00edfico que se encuentre en cualquier espacio p\u00fablico \u2013 aire libre o museo \u2013 del mundo y se recibir\u00e1n los trabajos hasta el 15 de abril&#8221;.<\/p>\n<p>Para finalizar el Decano de la Facultad de Artes, Dise\u00f1o y Ciencias de la Cultura de la Universidad Nacional del Nordeste. Federico Veirav\u00e9 indic\u00f3, &#8220;el fallo del jurado ser\u00e1 en mayo y el acto de entrega de premios en el mes de julio, todas las fechas, del a\u00f1o en curso&#8221;.<\/p>\n<p>Se otorgar\u00e1n obras escult\u00f3ricas de reconocidos artistas del Chaco a los primeros, segundos y terceros premios de cada rubro, diplomas y publicaci\u00f3n en antolog\u00eda de los premiados. El jurado otorgar\u00e1 las Menciones de Honor a las obras que considere, las que ser\u00e1n incluidas en la antolog\u00eda y se entregar\u00e1n diplomas a sus autores. Se entregar\u00e1n 5 ejemplares de la Antolog\u00eda a todos los escritores premiados.<\/p>\n<p>Para m\u00e1s informaci\u00f3n e inscripciones, solicitar m\u00e1s informaci\u00f3n al correo\u00a0<a href=\"mailto:sadechaco@yahoo.com\">sadechaco@yahoo.com<\/a>.[\/vc_column_text][vc_empty_space][vc_single_image image=&#8221;8622&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; qode_css_animation=&#8221;&#8221;][vc_empty_space][vc_empty_space][vc_column_text]Fuente: <a href=\"https:\/\/www.diariochaco.com\/noticia\/invitan-participar-de-concurso-de-cuentos-y-poesias-sobre-esculturas-del-mundo\" target=\"_blank\" rel=\"noopener\">https:\/\/www.diariochaco.com\/noticia\/invitan-participar-de-concurso-de-cuentos-y-poesias-sobre-esculturas-del-mundo<\/a><\/p>\n<p><a href=\"https:\/\/diarioprimeralinea.com.ar\/presentaron-el-concurso-de-cuentos-y-poesia-sobre-esculturas-del-mundo\/\" target=\"_blank\" rel=\"noopener\">https:\/\/diarioprimeralinea.com.ar\/presentaron-el-concurso-de-cuentos-y-poesia-sobre-esculturas-del-mundo\/<\/a><\/p>\n<p><a href=\"https:\/\/agenciafoco.com.ar\/detalle_noticia\/se-lanzo-el-concurso-de-cuentos-y-poesias-sobre-esculturas-del-mundo\" target=\"_blank\" rel=\"noopener\">https:\/\/agenciafoco.com.ar\/detalle_noticia\/se-lanzo-el-concurso-de-cuentos-y-poesias-sobre-esculturas-del-mundo<\/a><\/p>\n<p><a href=\"http:\/\/www.chacohoy.com\/noticias\/view\/261311\" target=\"_blank\" rel=\"noopener\">http:\/\/www.chacohoy.com\/noticias\/view\/261311<\/a><\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>Este jueves 24 de febrero, en la Fundaci\u00f3n Urunday, se realiz\u00f3 el lanzamiento de una nueva edici\u00f3n del Concurso Internacional &#8220;Premio Provincia del Chaco&#8221; de cuentos y poes\u00edas sobre una escultura.<\/p>\n","protected":false},"author":3,"featured_media":8620,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-8619","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novedades"],"_links":{"self":[{"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/posts\/8619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/comments?post=8619"}],"version-history":[{"count":4,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/posts\/8619\/revisions"}],"predecessor-version":[{"id":8637,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/posts\/8619\/revisions\/8637"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/media\/8620"}],"wp:attachment":[{"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/media?parent=8619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/categories?post=8619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/tags?post=8619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}