{"id":8677,"date":"2022-03-18T09:59:35","date_gmt":"2022-03-18T12:59:35","guid":{"rendered":"https:\/\/www.bienaldelchaco.org\/2024\/?p=8677"},"modified":"2022-03-18T10:04:01","modified_gmt":"2022-03-18T13:04:01","slug":"aunque-no-lo-crean-un-escultor-ucraniano-participaria-en-la-bienal-2022","status":"publish","type":"post","link":"https:\/\/www.bienaldelchaco.org\/2024\/aunque-no-lo-crean-un-escultor-ucraniano-participaria-en-la-bienal-2022\/","title":{"rendered":"&#8220;Aunque no lo crean&#8221;: Un escultor ucraniano participar\u00eda en la Bienal 2022"},"content":{"rendered":"<div class=\"vol-des\">El presidente de la Fundaci\u00f3n Urunday, que organiza el ansiado evento, asegur\u00f3 que en la lista de los diez artistas seleccionados hay uno oriundo de Ucrania. &#8220;Estamos superpendientes&#8221;, expres\u00f3 en di\u00e1logo con Radio Nordeste.<\/div>\n<div><\/div>\n<p><!--more-->[vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221;][vc_column][vc_column_text]A pocos meses de la <strong>Bienal Internacional de las Esculturas 2022<\/strong>\u00a0-que se realizar\u00e1 entre el 16 y el 23 de julio-, el presidente de la Fundaci\u00f3n Urunday,\u00a0<strong>Josese Eidman<\/strong>, dialog\u00f3 este jueves con\u00a0<strong>Radio Nordeste<\/strong>\u00a0y brind\u00f3 nuevos detalles sobre la organizaci\u00f3n del evento que cada dos a\u00f1os convoca a multitudes de visitantes y artistas de diferentes pa\u00edses.\u00a0<strong>Este a\u00f1o, seg\u00fan confirm\u00f3 Eidman, contar\u00eda con la presencia de un escultor ucraniano.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>En cuanto a los detalles de la organizaci\u00f3n del ansiado evento, Josese Eidman anticip\u00f3 que\u00a0<strong>lanzar\u00e1n la Bienal en Resistencia antes de que termine marzo.<\/strong>\u00a0Tambi\u00e9n se presentar\u00e1\u00a0<strong>en el Centro Cultural Kirchner de Buenos Aires en abril.\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Los escultores internacionales, seg\u00fan revel\u00f3, son diez, de m\u00e1s de 200 artistas de 70 pa\u00edses que se inscribieron.<\/strong>\u00a0\u201cLa convocatoria fue impresionante\u201d, asegur\u00f3. Y coment\u00f3 que entre los seleccionados hay participantes de\u00a0<strong>Albania, Argentina, M\u00e9xico, Corea del Sur, Eslovenia, Georgia, Rumania, Turqu\u00eda, y \u201caunque no crean hay un ucraniano\u201d<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p>Respecto al artista oriundo de Ucrania que fue seleccionado, debido al conflicto b\u00e9lico con Rusia, Josese asegur\u00f3 que \u201c<strong>estamos superpendientes de la situaci\u00f3n internacional<\/strong>, en primer lugar para que la tragedia termine lo antes posible, y en segundo lugar para poder contar con la presencia del artista que clasific\u00f3\u201d.<\/p>\n<p>&nbsp;<\/p>\n<blockquote>\n<h2>\u201cHoy tenemos 9 hect\u00e1reas pobladas de actividades art\u00edsticas y recreativas. Va a ser una verdadera celebraci\u00f3n.\u201d<\/h2>\n<p>&nbsp;<\/p><\/blockquote>\n<p>\u201c<strong>Estamos esperando ansiosamente y trabajando a full para que esta edici\u00f3n sea la mejor de todas<\/strong>\u201d, expres\u00f3 Eidman en comunicaci\u00f3n telef\u00f3nica, recordando que es la primera que se realiza de forma presencial despu\u00e9s de la pandemia del coronavirus.<\/p>\n<p>&nbsp;<\/p>\n<p>El titular de la Fundaci\u00f3n, quien debi\u00f3 suceder a\u00a0<strong>Fabriciano G\u00f3mez<\/strong>\u00a0en su cargo de presidente, destac\u00f3 la memoria del ic\u00f3nico escultor chaque\u00f1o que falleci\u00f3 en septiembre del a\u00f1o pasado. \u201cEsta es la Bienal de Fabriciano sin Fabriciano. Y nos pesa, nos cuesta.\u00a0<strong>Sin Fabri todo es mucho m\u00e1s dif\u00edcil, pero todo el equipo tiene claro lo que \u00e9l habr\u00eda querido, y estamos trabajando para honrar su legado<\/strong>\u201d, agreg\u00f3.[\/vc_column_text][vc_empty_space][vc_gallery interval=&#8221;3&#8243; images=&#8221;8678,8679,8680,8681,8682,8683&#8243; img_size=&#8221;full&#8221;][vc_empty_space][vc_column_text]Fuente:\u00a0 <a href=\"http:\/\/www.diario21.tv\/notix2\/noticia\/171576_quotaunque-no-lo-creanquot-un-escultor-ucraniano-participariacutea-en-la-bienal-2022.htm\" target=\"_blank\" rel=\"noopener\">http:\/\/www.diario21.tv\/notix2\/noticia\/171576_quotaunque-no-lo-creanquot-un-escultor-ucraniano-participariacutea-en-la-bienal-2022.htm<\/a>[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>El presidente de la Fundaci\u00f3n Urunday, que organiza el ansiado evento, asegur\u00f3 que en la lista de los diez artistas seleccionados hay uno oriundo de Ucrania. &#8220;Estamos superpendientes&#8221;, expres\u00f3 en di\u00e1logo con Radio Nordeste.<\/p>\n","protected":false},"author":3,"featured_media":8678,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-8677","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novedades"],"_links":{"self":[{"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/posts\/8677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/comments?post=8677"}],"version-history":[{"count":3,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/posts\/8677\/revisions"}],"predecessor-version":[{"id":8686,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/posts\/8677\/revisions\/8686"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/media\/8678"}],"wp:attachment":[{"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/media?parent=8677"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/categories?post=8677"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bienaldelchaco.org\/2024\/wp-json\/wp\/v2\/tags?post=8677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}